{"id":1072,"date":"2023-02-01T08:52:56","date_gmt":"2023-02-01T07:52:56","guid":{"rendered":"https:\/\/dogbed.de\/?p=1072"},"modified":"2023-03-28T16:45:09","modified_gmt":"2023-03-28T14:45:09","slug":"ein-paar-tipps-fuer-unterwegs","status":"publish","type":"post","link":"https:\/\/dogbed.de\/en\/ein-paar-tipps-fuer-unterwegs\/","title":{"rendered":"Ein paar Tipps f\u00fcr unterwegs"},"content":{"rendered":"<p>Ganz egal ob Sie die \u00fcbliche Mittagsrunde mit Ihrem Hund drehen oder ihn auf dem Campingplatz dabeihaben \u2013 Ihr Hund freut sich, wenn Sie ihm etwas bieten. Sie kennen Ihren Hund am besten: liebt er es, wenn Sie den Ball werfen? Oder ist er mit der Nase st\u00e4ndig am Boden? Nutzen Sie die Vorlieben Ihres Vierbeiners, oder probieren Sie auch mal etwas Neues aus.<\/p>\n\n\n\n<p>Nasenarbeit ist nicht nur beliebt bei Hunden, sondern lastet diese auch zus\u00e4tzlich aus. Hier k\u00f6nnen Sie kreativ werden: ob Sie einfach etwas Futter verstecken, oder gleich den Futterbeutel (den der Hund dann sucht und apportiert; dies muss vorher ge\u00fcbt werden) oder sogar F\u00e4hrtenarbeit mit Ihrem Hund machen \u2013 es st\u00e4rkt auf jeden Fall die Hund-Mensch-Beziehung, denn Futter ist ein wichtiges Privileg f\u00fcr Hunde. Einen Teil (oder alles) des Futters auf Spazierg\u00e4ngen zu f\u00fcttern, macht also auf jeden Fall Sinn, so wird Ihr Hund aufmerksamer (es k\u00f6nnte ja Futter geben!) und hat auch noch Spa\u00df dabei. *<\/p>\n\n\n\n<p>\u00dcben Sie Kommandos auf den Spazierg\u00e4ngen oder bringen Sie Ihrem Hund neue bei \u2013 auch das geht mit etwas Futter als Motivation oft leichter. Binden Sie, wenn m\u00f6glich, die Umgebung mit ein \u2013 lassen Sie Ihren Hund \u00fcber etwas balancieren, vielleicht liegt ja ein Baumstamm im Wald, der sich daf\u00fcr eignet, oder lassen Sie ihn auf einem Baumstumpf \u201eSitz\u201c machen und belohnen Sie ihn daf\u00fcr. Wichtig ist: es soll sowohl Ihnen als auch Ihrem Hund Spa\u00df machen \u2013 und ein bisschen Abwechslung macht jeden Ausflug interessanter. *Anmerkung: Dies gilt f\u00fcr gesunde Hunde und sollte individuell auf den Hund angepasst werden. Manche alte und\/oder kranke Hunde ben\u00f6tigen regelm\u00e4\u00dfige F\u00fctterungen.<\/p>","protected":false},"excerpt":{"rendered":"<p>Ganz egal ob Sie die \u00fcbliche Mittagsrunde mit Ihrem Hund drehen oder ihn auf dem Campingplatz dabeihaben \u2013 Ihr Hund freut sich, wenn Sie ihm etwas bieten. Sie kennen Ihren Hund am besten: liebt er es, wenn Sie den Ball werfen? Oder ist er mit der Nase st\u00e4ndig am Boden? Nutzen Sie die Vorlieben Ihres &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/dogbed.de\/en\/ein-paar-tipps-fuer-unterwegs\/\"> <span class=\"screen-reader-text\">Ein paar Tipps f\u00fcr unterwegs<\/span> Read More \u00bb<\/a><\/p>","protected":false},"author":2,"featured_media":1286,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1072","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ein paar Tipps f\u00fcr unterwegs | Dog-Bed by Disc-O-Bed<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dogbed.de\/en\/ein-paar-tipps-fuer-unterwegs\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ein paar Tipps f\u00fcr unterwegs | Dog-Bed by Disc-O-Bed\" \/>\n<meta property=\"og:description\" content=\"Ganz egal ob Sie die \u00fcbliche Mittagsrunde mit Ihrem Hund drehen oder ihn auf dem Campingplatz dabeihaben \u2013 Ihr Hund freut sich, wenn Sie ihm etwas bieten. Sie kennen Ihren Hund am besten: liebt er es, wenn Sie den Ball werfen? Oder ist er mit der Nase st\u00e4ndig am Boden? Nutzen Sie die Vorlieben Ihres &hellip; Ein paar Tipps f\u00fcr unterwegs Read More \u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dogbed.de\/en\/ein-paar-tipps-fuer-unterwegs\/\" \/>\n<meta property=\"og:site_name\" content=\"Dog-Bed by Disc-O-Bed\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/discobedeurope\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-01T07:52:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-28T14:45:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dogbed.de\/wp-content\/uploads\/2023\/02\/IMG_4873_tinified_1200x675.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jessica Mohme\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@discobed\" \/>\n<meta name=\"twitter:site\" content=\"@discobed\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jessica Mohme\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\/\/dogbed.de\/ein-paar-tipps-fuer-unterwegs\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dogbed.de\/ein-paar-tipps-fuer-unterwegs\/\"},\"author\":{\"name\":\"Jessica Mohme\",\"@id\":\"https:\/\/dogbed.de\/#\/schema\/person\/18a3945fb3816259ea9961bc3604ae41\"},\"headline\":\"Ein paar Tipps f\u00fcr unterwegs\",\"datePublished\":\"2023-02-01T07:52:56+00:00\",\"dateModified\":\"2023-03-28T14:45:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dogbed.de\/ein-paar-tipps-fuer-unterwegs\/\"},\"wordCount\":287,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dogbed.de\/#organization\"},\"articleSection\":[\"Allgemein\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dogbed.de\/ein-paar-tipps-fuer-unterwegs\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dogbed.de\/ein-paar-tipps-fuer-unterwegs\/\",\"url\":\"https:\/\/dogbed.de\/ein-paar-tipps-fuer-unterwegs\/\",\"name\":\"Ein paar Tipps f\u00fcr unterwegs | Dog-Bed by Disc-O-Bed\",\"isPartOf\":{\"@id\":\"https:\/\/dogbed.de\/#website\"},\"datePublished\":\"2023-02-01T07:52:56+00:00\",\"dateModified\":\"2023-03-28T14:45:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dogbed.de\/ein-paar-tipps-fuer-unterwegs\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dogbed.de\/ein-paar-tipps-fuer-unterwegs\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dogbed.de\/ein-paar-tipps-fuer-unterwegs\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/dogbed.de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ein paar Tipps f\u00fcr unterwegs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dogbed.de\/#website\",\"url\":\"https:\/\/dogbed.de\/\",\"name\":\"Dog-Bed by Disc-O-Bed\",\"description\":\"Damit Ihr Hund genauso komfortabel schlafen kann wie Sie selbst\",\"publisher\":{\"@id\":\"https:\/\/dogbed.de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dogbed.de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dogbed.de\/#organization\",\"name\":\"Disc-O-Bed EU GmbH\",\"url\":\"https:\/\/dogbed.de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/dogbed.de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dogbed.de\/wp-content\/uploads\/2022\/11\/cropped-cropped-Dog-Bed-Logo-rmvd-BG.png\",\"contentUrl\":\"https:\/\/dogbed.de\/wp-content\/uploads\/2022\/11\/cropped-cropped-Dog-Bed-Logo-rmvd-BG.png\",\"width\":827,\"height\":282,\"caption\":\"Disc-O-Bed EU GmbH\"},\"image\":{\"@id\":\"https:\/\/dogbed.de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/discobedeurope\",\"https:\/\/twitter.com\/discobed\",\"https:\/\/www.instagram.com\/discobed_europe\/\",\"https:\/\/www.youtube.com\/channel\/UCByErzLvXvKpELD_WJSceKQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/dogbed.de\/#\/schema\/person\/18a3945fb3816259ea9961bc3604ae41\",\"name\":\"Jessica Mohme\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/dogbed.de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ddc3625e40c0a251ca06be2b6e6942bce727278a3b517c6b4c3f136595e5bffa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ddc3625e40c0a251ca06be2b6e6942bce727278a3b517c6b4c3f136595e5bffa?s=96&d=mm&r=g\",\"caption\":\"Jessica Mohme\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ein paar Tipps f\u00fcr unterwegs | Dog-Bed by Disc-O-Bed","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dogbed.de\/en\/ein-paar-tipps-fuer-unterwegs\/","og_locale":"en_US","og_type":"article","og_title":"Ein paar Tipps f\u00fcr unterwegs | Dog-Bed by Disc-O-Bed","og_description":"Ganz egal ob Sie die \u00fcbliche Mittagsrunde mit Ihrem Hund drehen oder ihn auf dem Campingplatz dabeihaben \u2013 Ihr Hund freut sich, wenn Sie ihm etwas bieten. Sie kennen Ihren Hund am besten: liebt er es, wenn Sie den Ball werfen? Oder ist er mit der Nase st\u00e4ndig am Boden? Nutzen Sie die Vorlieben Ihres &hellip; Ein paar Tipps f\u00fcr unterwegs Read More \u00bb","og_url":"https:\/\/dogbed.de\/en\/ein-paar-tipps-fuer-unterwegs\/","og_site_name":"Dog-Bed by Disc-O-Bed","article_publisher":"https:\/\/www.facebook.com\/discobedeurope","article_published_time":"2023-02-01T07:52:56+00:00","article_modified_time":"2023-03-28T14:45:09+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/dogbed.de\/wp-content\/uploads\/2023\/02\/IMG_4873_tinified_1200x675.jpg","type":"image\/jpeg"}],"author":"Jessica Mohme","twitter_card":"summary_large_image","twitter_creator":"@discobed","twitter_site":"@discobed","twitter_misc":{"Written by":"Jessica Mohme","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/dogbed.de\/ein-paar-tipps-fuer-unterwegs\/#article","isPartOf":{"@id":"https:\/\/dogbed.de\/ein-paar-tipps-fuer-unterwegs\/"},"author":{"name":"Jessica Mohme","@id":"https:\/\/dogbed.de\/#\/schema\/person\/18a3945fb3816259ea9961bc3604ae41"},"headline":"Ein paar Tipps f\u00fcr unterwegs","datePublished":"2023-02-01T07:52:56+00:00","dateModified":"2023-03-28T14:45:09+00:00","mainEntityOfPage":{"@id":"https:\/\/dogbed.de\/ein-paar-tipps-fuer-unterwegs\/"},"wordCount":287,"commentCount":0,"publisher":{"@id":"https:\/\/dogbed.de\/#organization"},"articleSection":["Allgemein"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dogbed.de\/ein-paar-tipps-fuer-unterwegs\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dogbed.de\/ein-paar-tipps-fuer-unterwegs\/","url":"https:\/\/dogbed.de\/ein-paar-tipps-fuer-unterwegs\/","name":"Ein paar Tipps f\u00fcr unterwegs | Dog-Bed by Disc-O-Bed","isPartOf":{"@id":"https:\/\/dogbed.de\/#website"},"datePublished":"2023-02-01T07:52:56+00:00","dateModified":"2023-03-28T14:45:09+00:00","breadcrumb":{"@id":"https:\/\/dogbed.de\/ein-paar-tipps-fuer-unterwegs\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dogbed.de\/ein-paar-tipps-fuer-unterwegs\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dogbed.de\/ein-paar-tipps-fuer-unterwegs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/dogbed.de\/"},{"@type":"ListItem","position":2,"name":"Ein paar Tipps f\u00fcr unterwegs"}]},{"@type":"WebSite","@id":"https:\/\/dogbed.de\/#website","url":"https:\/\/dogbed.de\/","name":"Dog-Bed by Disc-O-Bed","description":"Damit Ihr Hund genauso komfortabel schlafen kann wie Sie selbst","publisher":{"@id":"https:\/\/dogbed.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dogbed.de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dogbed.de\/#organization","name":"Disc-O-Bed EU GmbH","url":"https:\/\/dogbed.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dogbed.de\/#\/schema\/logo\/image\/","url":"https:\/\/dogbed.de\/wp-content\/uploads\/2022\/11\/cropped-cropped-Dog-Bed-Logo-rmvd-BG.png","contentUrl":"https:\/\/dogbed.de\/wp-content\/uploads\/2022\/11\/cropped-cropped-Dog-Bed-Logo-rmvd-BG.png","width":827,"height":282,"caption":"Disc-O-Bed EU GmbH"},"image":{"@id":"https:\/\/dogbed.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/discobedeurope","https:\/\/twitter.com\/discobed","https:\/\/www.instagram.com\/discobed_europe\/","https:\/\/www.youtube.com\/channel\/UCByErzLvXvKpELD_WJSceKQ"]},{"@type":"Person","@id":"https:\/\/dogbed.de\/#\/schema\/person\/18a3945fb3816259ea9961bc3604ae41","name":"Jessica Mohme","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dogbed.de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ddc3625e40c0a251ca06be2b6e6942bce727278a3b517c6b4c3f136595e5bffa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ddc3625e40c0a251ca06be2b6e6942bce727278a3b517c6b4c3f136595e5bffa?s=96&d=mm&r=g","caption":"Jessica Mohme"}}]}},"_links":{"self":[{"href":"https:\/\/dogbed.de\/en\/wp-json\/wp\/v2\/posts\/1072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dogbed.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dogbed.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dogbed.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dogbed.de\/en\/wp-json\/wp\/v2\/comments?post=1072"}],"version-history":[{"count":2,"href":"https:\/\/dogbed.de\/en\/wp-json\/wp\/v2\/posts\/1072\/revisions"}],"predecessor-version":[{"id":1074,"href":"https:\/\/dogbed.de\/en\/wp-json\/wp\/v2\/posts\/1072\/revisions\/1074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dogbed.de\/en\/wp-json\/wp\/v2\/media\/1286"}],"wp:attachment":[{"href":"https:\/\/dogbed.de\/en\/wp-json\/wp\/v2\/media?parent=1072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dogbed.de\/en\/wp-json\/wp\/v2\/categories?post=1072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dogbed.de\/en\/wp-json\/wp\/v2\/tags?post=1072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}